{"id":21755,"date":"2019-10-16T16:44:47","date_gmt":"2019-10-16T15:44:47","guid":{"rendered":"https:\/\/www.nissan-couriant.fr\/blog\/?p=21755"},"modified":"2019-10-16T16:46:20","modified_gmt":"2019-10-16T15:46:20","slug":"nissan-couriant-salon-du-deux-roues-arena","status":"publish","type":"post","link":"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/","title":{"rendered":"Retrouvez Nissan Couriant au Salon du Deux Roues ce week-end \u00e0 l&rsquo;Arena"},"content":{"rendered":"<p>Pour sa premi\u00e8re \u00e9dition, le Salon du Deux Roues\u00a0et du Quad accueille votre concession Nissan Couriant. Le samedi 19 et le dimanche 20 octobre de 11h \u00e0 19h, Nissan Aix-en-Provence est ravi d&rsquo;exposer deux v\u00e9hicules clairement off-road.<\/p>\n<h2>Nissan NAVARA double Cab et NAVARA NGUARD OFF ROADER AT32<\/h2>\n<p>Le <strong><a href=\"https:\/\/www.nissan-couriant.fr\/gamme\/navara-54\">Nissan NAVARA<\/a><\/strong>, le pick-up robuste et intelligent par Nissan. Avec une capacit\u00e9 de remorquage maximale de 3 500 kg, ses transmissions 4&#215;4 \u00e0 et son blocage de diff\u00e9rentiel arri\u00e8re, emportez tout ce dont vous avez besoin, o\u00f9 vous le souhaitez. Que ce soit pour le travail ou les loisirs, vous appr\u00e9cierez la capacit\u00e9 de remorquage g\u00e9n\u00e9reuse de 3,5 tonnes du Nissan NAVARA. Avec sa capacit\u00e9 exceptionnelle, il pourra vous accompagner dans toutes vos aventures sans jamais abandonner une partie de votre chargement.<\/p>\n<p>Encore plus robuste, le <strong>Nissan NAVARA NGUARD OFF-ROADER AT32<\/strong> a \u00e9t\u00e9 con\u00e7u sp\u00e9cialement en collaboration avec Arctic Trucks pour r\u00e9sister aux terrains les plus exigeants. Repoussez les fronti\u00e8res du possible gr\u00e2ce aux roues 32&Prime;, aux suspensions renforc\u00e9es, \u00e0 la protection de soubassement et \u00e0 bien d\u2019autres caract\u00e9ristiques. Ce pick-up est un v\u00e9ritable concentr\u00e9 de puissance.<br \/>\nEmportez vos montures dans les environnements les plus rudes avec la Nissan Navara NGUARD AT32.<\/p>\n<h2>Une premi\u00e8re \u00e9dition prometteuse<\/h2>\n<p>Apr\u00e8s le succ\u00e8s grandissant du \u00ab\u00a0Salon de la Moto et du Scooter\u00a0\u00bb de Marseille qui a f\u00eat\u00e9 ses 10 ans en mars dernier, le Groupe \u00ab\u00a0La Provence\u00a0\u00bb lance le \u00ab\u00a0Salon du deux roues et du Quad\u00a0\u00bb, ce week-end \u00e0 l&rsquo;Arena du Pays d&rsquo;Aix, id\u00e9alement situ\u00e9e pour le public, \u00e0 10km d&rsquo;Aix-en-Provence et 20 km de Marseille.<\/p>\n<p>C&rsquo;est le lieu de r\u00e9sidence du PAUC, qui a offert au club aixois un cadre majestueux au sein duquel il a pris une nouvelle dimension. Un \u00e9crin dans lequel va na\u00eetre le Salon du 2 Roues et du Quad, ce week-end, pour une premi\u00e8re \u00e9dition tr\u00e8s prometteuse, organis\u00e9e par \u00ab\u00a0La Provence\u00a0\u00bb. L&rsquo;espace de deux jours, samedi et dimanche, l&rsquo;Arena du Pays d&rsquo;Aix va voir d\u00e9ferler un concentr\u00e9 du monde du deux-roues, o\u00f9 il y en aura forc\u00e9ment pour tous les go\u00fbts. Et toutes les envies.<\/p>\n<p>\u00c9videmment, les grands classiques seront pr\u00e9sents. Des routi\u00e8res, des sportives, des tout-terrain, toutes les d\u00e9clinaisons du deux-roues seront pr\u00e9sentes au rendez-vous, qu&rsquo;elles soient japonaises, am\u00e9ricaines, italiennes ou fran\u00e7aises.<\/p>\n<p>Nous vous attendons nombreux tout le week-end !<\/p>\n<p>Entr\u00e9e : 5\u00a0euros (gratuit pour les &#8211; 12\u00a0ans), pr\u00e9vente \u00e0 3\u00a0euros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour sa premi\u00e8re \u00e9dition, le Salon du Deux Roues\u00a0et du Quad accueille votre concession Nissan Couriant. Le samedi 19 et le dimanche 20 octobre de 11h \u00e0 19h, Nissan Aix-en-Provence&#8230;<\/p>\n","protected":false},"author":1101,"featured_media":21756,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,17],"tags":[],"class_list":["post-21755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events","category-nissancouriant"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Retrouvez Nissan Couriant au Salon du Deux Roues ce week-end \u00e0 l&#039;Arena - Nissan Couriant Aix en Provence<\/title>\n<meta name=\"description\" content=\"Pour sa premi\u00e8re \u00e9dition, le Salon du Deux Roues\u00a0et du Quad accueille votre concession Nissan Couriant. Le samedi 19 et le dimanche 20 octobre de 11h \u00e0 19h, Nissan Aix-en-Provence est ravi d&#039;exposer deux v\u00e9hicules directement inspir\u00e9s du monde de l&#039;off-road.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retrouvez Nissan Couriant au Salon du Deux Roues ce week-end \u00e0 l&#039;Arena - Nissan Couriant Aix en Provence\" \/>\n<meta property=\"og:description\" content=\"Pour sa premi\u00e8re \u00e9dition, le Salon du Deux Roues\u00a0et du Quad accueille votre concession Nissan Couriant. Le samedi 19 et le dimanche 20 octobre de 11h \u00e0 19h, Nissan Aix-en-Provence est ravi d&#039;exposer deux v\u00e9hicules directement inspir\u00e9s du monde de l&#039;off-road.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/\" \/>\n<meta property=\"og:site_name\" content=\"Nissan Couriant Aix en Provence\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nissancouriant\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-16T15:44:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-16T15:46:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nissan-couriant.fr\/blog\/wp-content\/uploads\/2019\/10\/header-salon-moto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"596\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NissanCouriant\" \/>\n<meta name=\"twitter:site\" content=\"@NissanCouriant\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/\",\"url\":\"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/\",\"name\":\"Retrouvez Nissan Couriant au Salon du Deux Roues ce week-end \u00e0 l'Arena - Nissan Couriant Aix en Provence\",\"isPartOf\":{\"@id\":\"https:\/\/www.nissan-couriant.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nissan-couriant.fr\/blog\/wp-content\/uploads\/2019\/10\/header-salon-moto.jpg\",\"datePublished\":\"2019-10-16T15:44:47+00:00\",\"dateModified\":\"2019-10-16T15:46:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.nissan-couriant.fr\/blog\/#\/schema\/person\/41a03274ac74ba26549677c01c8c8f95\"},\"description\":\"Pour sa premi\u00e8re \u00e9dition, le Salon du Deux Roues\u00a0et du Quad accueille votre concession Nissan Couriant. Le samedi 19 et le dimanche 20 octobre de 11h \u00e0 19h, Nissan Aix-en-Provence est ravi d'exposer deux v\u00e9hicules directement inspir\u00e9s du monde de l'off-road.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/#primaryimage\",\"url\":\"https:\/\/www.nissan-couriant.fr\/blog\/wp-content\/uploads\/2019\/10\/header-salon-moto.jpg\",\"contentUrl\":\"https:\/\/www.nissan-couriant.fr\/blog\/wp-content\/uploads\/2019\/10\/header-salon-moto.jpg\",\"width\":1400,\"height\":596},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.nissan-couriant.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retrouvez Nissan Couriant au Salon du Deux Roues ce week-end \u00e0 l&rsquo;Arena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nissan-couriant.fr\/blog\/#website\",\"url\":\"https:\/\/www.nissan-couriant.fr\/blog\/\",\"name\":\"Nissan Couriant Aix en Provence\",\"description\":\"Distributeur Nissan \u00e0 Aix en Provence et Pays d&#039;Aix, v\u00e9hicules neufs et d&#039;occasion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nissan-couriant.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nissan-couriant.fr\/blog\/#\/schema\/person\/41a03274ac74ba26549677c01c8c8f95\",\"name\":\"Laura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.nissan-couriant.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/efc9f8844553d88b37d54276fd17d9c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/efc9f8844553d88b37d54276fd17d9c7?s=96&d=mm&r=g\",\"caption\":\"Laura\"},\"url\":\"https:\/\/www.nissan-couriant.fr\/blog\/author\/laura\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retrouvez Nissan Couriant au Salon du Deux Roues ce week-end \u00e0 l'Arena - Nissan Couriant Aix en Provence","description":"Pour sa premi\u00e8re \u00e9dition, le Salon du Deux Roues\u00a0et du Quad accueille votre concession Nissan Couriant. Le samedi 19 et le dimanche 20 octobre de 11h \u00e0 19h, Nissan Aix-en-Provence est ravi d'exposer deux v\u00e9hicules directement inspir\u00e9s du monde de l'off-road.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/","og_locale":"fr_FR","og_type":"article","og_title":"Retrouvez Nissan Couriant au Salon du Deux Roues ce week-end \u00e0 l'Arena - Nissan Couriant Aix en Provence","og_description":"Pour sa premi\u00e8re \u00e9dition, le Salon du Deux Roues\u00a0et du Quad accueille votre concession Nissan Couriant. Le samedi 19 et le dimanche 20 octobre de 11h \u00e0 19h, Nissan Aix-en-Provence est ravi d'exposer deux v\u00e9hicules directement inspir\u00e9s du monde de l'off-road.\u00a0","og_url":"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/","og_site_name":"Nissan Couriant Aix en Provence","article_publisher":"https:\/\/www.facebook.com\/nissancouriant","article_published_time":"2019-10-16T15:44:47+00:00","article_modified_time":"2019-10-16T15:46:20+00:00","og_image":[{"width":1400,"height":596,"url":"https:\/\/www.nissan-couriant.fr\/blog\/wp-content\/uploads\/2019\/10\/header-salon-moto.jpg","type":"image\/jpeg"}],"author":"Laura","twitter_card":"summary_large_image","twitter_creator":"@NissanCouriant","twitter_site":"@NissanCouriant","twitter_misc":{"\u00c9crit par":"Laura","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/","url":"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/","name":"Retrouvez Nissan Couriant au Salon du Deux Roues ce week-end \u00e0 l'Arena - Nissan Couriant Aix en Provence","isPartOf":{"@id":"https:\/\/www.nissan-couriant.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/#primaryimage"},"image":{"@id":"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nissan-couriant.fr\/blog\/wp-content\/uploads\/2019\/10\/header-salon-moto.jpg","datePublished":"2019-10-16T15:44:47+00:00","dateModified":"2019-10-16T15:46:20+00:00","author":{"@id":"https:\/\/www.nissan-couriant.fr\/blog\/#\/schema\/person\/41a03274ac74ba26549677c01c8c8f95"},"description":"Pour sa premi\u00e8re \u00e9dition, le Salon du Deux Roues\u00a0et du Quad accueille votre concession Nissan Couriant. Le samedi 19 et le dimanche 20 octobre de 11h \u00e0 19h, Nissan Aix-en-Provence est ravi d'exposer deux v\u00e9hicules directement inspir\u00e9s du monde de l'off-road.\u00a0","breadcrumb":{"@id":"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/#primaryimage","url":"https:\/\/www.nissan-couriant.fr\/blog\/wp-content\/uploads\/2019\/10\/header-salon-moto.jpg","contentUrl":"https:\/\/www.nissan-couriant.fr\/blog\/wp-content\/uploads\/2019\/10\/header-salon-moto.jpg","width":1400,"height":596},{"@type":"BreadcrumbList","@id":"https:\/\/www.nissan-couriant.fr\/blog\/2019\/10\/16\/nissan-couriant-salon-du-deux-roues-arena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.nissan-couriant.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Retrouvez Nissan Couriant au Salon du Deux Roues ce week-end \u00e0 l&rsquo;Arena"}]},{"@type":"WebSite","@id":"https:\/\/www.nissan-couriant.fr\/blog\/#website","url":"https:\/\/www.nissan-couriant.fr\/blog\/","name":"Nissan Couriant Aix en Provence","description":"Distributeur Nissan \u00e0 Aix en Provence et Pays d&#039;Aix, v\u00e9hicules neufs et d&#039;occasion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nissan-couriant.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.nissan-couriant.fr\/blog\/#\/schema\/person\/41a03274ac74ba26549677c01c8c8f95","name":"Laura","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.nissan-couriant.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/efc9f8844553d88b37d54276fd17d9c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efc9f8844553d88b37d54276fd17d9c7?s=96&d=mm&r=g","caption":"Laura"},"url":"https:\/\/www.nissan-couriant.fr\/blog\/author\/laura\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:05:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.nissan-couriant.fr\/blog\/wp-json\/wp\/v2\/posts\/21755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nissan-couriant.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nissan-couriant.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nissan-couriant.fr\/blog\/wp-json\/wp\/v2\/users\/1101"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nissan-couriant.fr\/blog\/wp-json\/wp\/v2\/comments?post=21755"}],"version-history":[{"count":2,"href":"https:\/\/www.nissan-couriant.fr\/blog\/wp-json\/wp\/v2\/posts\/21755\/revisions"}],"predecessor-version":[{"id":21758,"href":"https:\/\/www.nissan-couriant.fr\/blog\/wp-json\/wp\/v2\/posts\/21755\/revisions\/21758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nissan-couriant.fr\/blog\/wp-json\/wp\/v2\/media\/21756"}],"wp:attachment":[{"href":"https:\/\/www.nissan-couriant.fr\/blog\/wp-json\/wp\/v2\/media?parent=21755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nissan-couriant.fr\/blog\/wp-json\/wp\/v2\/categories?post=21755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nissan-couriant.fr\/blog\/wp-json\/wp\/v2\/tags?post=21755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}